{"id":1040,"date":"2020-04-29T16:12:44","date_gmt":"2020-04-29T20:12:44","guid":{"rendered":"https:\/\/handsandthecity.cl\/ha\/?post_type=product&#038;p=1040"},"modified":"2020-06-04T16:39:30","modified_gmt":"2020-06-04T20:39:30","slug":"mascarilla-hidratante","status":"publish","type":"product","link":"https:\/\/handsandthecity.cl\/ha\/producto\/mascarilla-hidratante\/","title":{"rendered":"Mascarilla Cabellos Tratados"},"content":{"rendered":"<h4 class=\"vc_custom_heading\"><strong>MODO DE EMPLEO<\/strong><\/h4>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Despu\u00e9s del lavado, aplica\u00a0la\u00a0<strong>Mascarilla Cabellos Tratados<\/strong><strong>\u00a0<\/strong>por todo el tallo capilar, sin tocar el cuero cabelludo. Peina para repartir y deja unos minutos de tiempo de exposici\u00f3n. Enjuaga con agua tibia y procede al peinado.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p class=\"vc_custom_heading\"><strong>Cuida y recupera tu cabello tratado<\/strong><\/p>\n<p class=\"vc_custom_heading\">M\u00e1s suavidad, nutrici\u00f3n y brillo<\/p>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p><strong>Mascarilla Cabellos Tratados<\/strong><strong>\u00a0<\/strong>es una mascarilla formulada a base de activo protector del color y reparador de la fibra capilar ideal para cabellos con color o con otros trabajos t\u00e9cnicos. Su f\u00f3rmula con aceite de macadamia y extracto de bayas rojas recupera el aspecto sano del tallo capilar, aumentando la resistencia a la oxidaci\u00f3n.<\/p>\n<p>Recomendado\u00a0tras per\u00edodos de exposici\u00f3n en piscinas, mar, etc.<\/p>\n<\/div>\n<\/div>\n","protected":false},"featured_media":1044,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[28],"product_tag":[],"class_list":{"0":"post-1040","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-capilar","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/handsandthecity.cl\/ha\/wp-json\/wp\/v2\/product\/1040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/handsandthecity.cl\/ha\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/handsandthecity.cl\/ha\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/handsandthecity.cl\/ha\/wp-json\/wp\/v2\/comments?post=1040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/handsandthecity.cl\/ha\/wp-json\/wp\/v2\/media\/1044"}],"wp:attachment":[{"href":"https:\/\/handsandthecity.cl\/ha\/wp-json\/wp\/v2\/media?parent=1040"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/handsandthecity.cl\/ha\/wp-json\/wp\/v2\/product_brand?post=1040"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/handsandthecity.cl\/ha\/wp-json\/wp\/v2\/product_cat?post=1040"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/handsandthecity.cl\/ha\/wp-json\/wp\/v2\/product_tag?post=1040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}